{"id":98,"count":6,"description":"","link":"https:\/\/www.destinationirvine.com\/ja\/eventastic_organizers\/broken-yolk-cafe\/","name":"\u30d6\u30ed\u30fc\u30af\u30f3\u30fb\u30e8\u30eb\u30af\u30fb\u30ab\u30d5\u30a7","slug":"broken-yolk-cafe","taxonomy":"eventastic_organizers","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Broken Yolk Cafe Archives - Destination Irvine<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Broken Yolk Cafe Archives - Destination Irvine\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.destinationirvine.com\/ja\/eventastic_organizers\/broken-yolk-cafe\/\" \/>\n<meta property=\"og:site_name\" content=\"Destination Irvine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/www.destinationirvine.com\/eventastic_organizers\/broken-yolk-cafe\/\",\"url\":\"http:\/\/www.destinationirvine.com\/eventastic_organizers\/broken-yolk-cafe\/\",\"name\":\"Broken Yolk Cafe Archives - Destination Irvine\",\"isPartOf\":{\"@id\":\"https:\/\/www.destinationirvine.com\/ko\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.destinationirvine.com\/eventastic_organizers\/broken-yolk-cafe\/#breadcrumb\"},\"inLanguage\":\"ja\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.destinationirvine.com\/eventastic_organizers\/broken-yolk-cafe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.destinationirvine.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Broken Yolk Cafe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.destinationirvine.com\/ko\/#website\",\"url\":\"https:\/\/www.destinationirvine.com\/ko\/\",\"name\":\"Destination Irvine\",\"description\":\"The Official Tourism Partner for Irvine, California - SoCal\",\"publisher\":{\"@id\":\"https:\/\/www.destinationirvine.com\/ko\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.destinationirvine.com\/ko\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.destinationirvine.com\/ko\/#organization\",\"name\":\"Destination Irvine\",\"url\":\"https:\/\/www.destinationirvine.com\/ko\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\/\/www.destinationirvine.com\/ko\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.destinationirvine.com\/wp-content\/uploads\/2025\/08\/destination-irvine-logo.svg\",\"contentUrl\":\"https:\/\/www.destinationirvine.com\/wp-content\/uploads\/2025\/08\/destination-irvine-logo.svg\",\"caption\":\"Destination Irvine\"},\"image\":{\"@id\":\"https:\/\/www.destinationirvine.com\/ko\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/destinationirvine\/\",\"https:\/\/www.youtube.com\/user\/DestinationIrvine\",\"https:\/\/www.tripadvisor.com\/Tourism-g32530-Irvine_California-Vacations.html\",\"https:\/\/www.linkedin.com\/company\/destination-irvine\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Broken Yolk Cafe Archives - Destination Irvine","robots":{"index":"noindex","follow":"follow"},"og_locale":"ja_JP","og_type":"article","og_title":"Broken Yolk Cafe Archives - Destination Irvine","og_url":"http:\/\/www.destinationirvine.com\/ja\/eventastic_organizers\/broken-yolk-cafe\/","og_site_name":"Destination Irvine","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/www.destinationirvine.com\/eventastic_organizers\/broken-yolk-cafe\/","url":"http:\/\/www.destinationirvine.com\/eventastic_organizers\/broken-yolk-cafe\/","name":"Broken Yolk Cafe Archives - Destination Irvine","isPartOf":{"@id":"https:\/\/www.destinationirvine.com\/ko\/#website"},"breadcrumb":{"@id":"http:\/\/www.destinationirvine.com\/eventastic_organizers\/broken-yolk-cafe\/#breadcrumb"},"inLanguage":"ja"},{"@type":"BreadcrumbList","@id":"http:\/\/www.destinationirvine.com\/eventastic_organizers\/broken-yolk-cafe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.destinationirvine.com\/"},{"@type":"ListItem","position":2,"name":"Broken Yolk Cafe"}]},{"@type":"WebSite","@id":"https:\/\/www.destinationirvine.com\/ko\/#website","url":"https:\/\/www.destinationirvine.com\/ko\/","name":"Destination Irvine","description":"The Official Tourism Partner for Irvine, California - SoCal","publisher":{"@id":"https:\/\/www.destinationirvine.com\/ko\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.destinationirvine.com\/ko\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/www.destinationirvine.com\/ko\/#organization","name":"Destination Irvine","url":"https:\/\/www.destinationirvine.com\/ko\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.destinationirvine.com\/ko\/#\/schema\/logo\/image\/","url":"https:\/\/www.destinationirvine.com\/wp-content\/uploads\/2025\/08\/destination-irvine-logo.svg","contentUrl":"https:\/\/www.destinationirvine.com\/wp-content\/uploads\/2025\/08\/destination-irvine-logo.svg","caption":"Destination Irvine"},"image":{"@id":"https:\/\/www.destinationirvine.com\/ko\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/destinationirvine\/","https:\/\/www.youtube.com\/user\/DestinationIrvine","https:\/\/www.tripadvisor.com\/Tourism-g32530-Irvine_California-Vacations.html","https:\/\/www.linkedin.com\/company\/destination-irvine\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.destinationirvine.com\/ja\/wp-json\/wp\/v2\/eventastic_organizers\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.destinationirvine.com\/ja\/wp-json\/wp\/v2\/eventastic_organizers"}],"about":[{"href":"https:\/\/www.destinationirvine.com\/ja\/wp-json\/wp\/v2\/taxonomies\/eventastic_organizers"}],"wp:post_type":[{"href":"https:\/\/www.destinationirvine.com\/ja\/wp-json\/wp\/v2\/event?eventastic_organizers=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}